{"id":1796,"date":"2023-05-12T03:00:31","date_gmt":"2023-05-12T03:00:31","guid":{"rendered":"https:\/\/hubo-sports.com\/?page_id=1796"},"modified":"2024-11-11T14:31:25","modified_gmt":"2024-11-11T06:31:25","slug":"contact-us","status":"publish","type":"page","link":"https:\/\/hubo-sports.com\/fr\/contact-us\/","title":{"rendered":"Contactez-nous"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1796\" class=\"elementor elementor-1796\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-354c439 e-flex e-con-boxed e-con e-parent\" data-id=\"354c439\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc8da8f elementor-widget elementor-widget-inf_breadcrumbs\" data-id=\"bc8da8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"inf_breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div id=\"infility_position\" class=''>\n\t\t\t\t\t\t\t\t\t\t\t<p class='0'>\n\t\t\t\t\t<a href=\"\/fr\/\" >\t\t\t\t\t\tMaison\t\t\t\t\t<\/a>\t\t\t\t<\/p>\n\t\t\t\t\t\t\t <span>><\/span> \t\t\t\t<p class='this'>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e942cd6 e-flex e-con-boxed e-con e-parent\" data-id=\"e942cd6\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ef371c4 e-flex e-con-boxed e-con e-parent\" data-id=\"ef371c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72998e5 elementor-vertical-align-top elementor-widget elementor-widget-image-box\" data-id=\"72998e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h1 class=\"elementor-image-box-title\">Le succ\u00e8s de vos lunettes commence avec Hubo<\/h1><p class=\"elementor-image-box-description\">Pour Hubo, produire des lunettes de qualit\u00e9 ne suffit pas. Notre objectif est de vous offrir des services et des solutions de la plus haute qualit\u00e9 pour r\u00e9pondre \u00e0 vos besoins. Confiez-nous la recherche de lunettes adapt\u00e9es \u00e0 votre projet\u00a0!<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-176d3f9 e-flex e-con-boxed e-con e-parent\" data-id=\"176d3f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cb68c1b e-flex e-con-boxed e-con e-parent\" data-id=\"cb68c1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a4fff79 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"a4fff79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/safety-goggles1.webp\" class=\"attachment-full size-full wp-image-1811\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Des produits exceptionnels<\/h2><p class=\"elementor-image-box-description\">De l&#039;approvisionnement en mati\u00e8res premi\u00e8res au contr\u00f4le qualit\u00e9 strict sur la ligne de production, nous prenons une garantie suppl\u00e9mentaire pour vous fournir les meilleures lunettes sur lesquelles votre marque peut compter.\n<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c74fee e-flex e-con-boxed e-con e-parent\" data-id=\"1c74fee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-04196e8 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"04196e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/protection-2.webp\" class=\"attachment-full size-full wp-image-1810\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h2 class=\"elementor-image-box-title\">Services m\u00e9ticuleux<\/h2><p class=\"elementor-image-box-description\">Forts de plus de 10 ans d&#039;exp\u00e9rience dans le secteur, nous ne nous limitons pas \u00e0 proposer des lunettes haut de gamme. Nous proposons \u00e9galement des services complets OEM, ODM et marques de distributeur.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b6138e e-flex e-con-boxed e-con e-parent\" data-id=\"8b6138e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c5ceb07 pp-contact-form-7-button-custom elementor-widget elementor-widget-pp-contact-form-7\" data-id=\"c5ceb07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"pp-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"pp-contact-form pp-contact-form-7 placeholder-show\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"pp-contact-form-7-heading\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"pp-contact-form-title pp-contact-form-7-title\">\n\t\t\t\t\t\t\t\t\tContactez-nous\t\t\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f10-p1796-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"10\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/contact-us\/#wpcf7-f10-p1796-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/contact-us\/#wpcf7-f10-p1796-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"10\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f10-p1796-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"1796\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p><label w=\"50\" style=\"color: #54595F;\"> Votre nom* <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n<\/p>\n<p><label w=\"50\" style=\"color: #54595F;\"> Nom de l&#039;entreprise <span class=\"wpcf7-form-control-wrap\" data-name=\"your-company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-company\" \/><\/span> <\/label>\n<\/p>\n<p><label w=\"50\" style=\"color: #54595F;\"> Votre e-mail* <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label w=\"50\" style=\"color: #54595F;\"> Votre t\u00e9l\u00e9phone*<span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-phone\" \/><\/span><\/label>\n<\/p>\n<p><label style=\"color: #54595F;\"> Message* <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Soumettre\" \/>\n<\/p><p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"102\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div><textarea name=\"page_source\" class=\"hide_field no_translate\"><\/textarea>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-264a7fa elementor-widget elementor-widget-text-editor\" data-id=\"264a7fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t*Nous respectons votre confidentialit\u00e9 et toutes les informations sont prot\u00e9g\u00e9es.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Home > Your goggles success starts with Hubo For Hubo, it goes beyond just producing great goggles. We aim to provide the best quality services and solutions to meet your needs, so let us find the right goggle solution for your project! Exceptional Products From raw materials sourcing to strict quality control on the production [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"two_page_speed":[],"footnotes":""},"class_list":["post-1796","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact Us | Hubo Goggle Manufacturer<\/title>\n<meta name=\"description\" content=\"Need any assistance with custom ski goggles, free samples, or startup? The experienced Hubo team is here to help. Click to drop us a line.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hubo-sports.com\/fr\/contact-us\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact Us | Hubo Goggle Manufacturer\" \/>\n<meta property=\"og:description\" content=\"Need any assistance with custom ski goggles, free samples, or startup? The experienced Hubo team is here to help. Click to drop us a line.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hubo-sports.com\/fr\/contact-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Hubo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-11T06:31:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/safety-goggles1.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/\",\"url\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/\",\"name\":\"Contact Us | Hubo Goggle Manufacturer\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hubo-sports.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/safety-goggles1.webp\",\"datePublished\":\"2023-05-12T03:00:31+00:00\",\"dateModified\":\"2024-11-11T06:31:25+00:00\",\"description\":\"Need any assistance with custom ski goggles, free samples, or startup? The experienced Hubo team is here to help. Click to drop us a line.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hubo-sports.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/safety-goggles1.webp\",\"contentUrl\":\"https:\\\/\\\/hubo-sports.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/safety-goggles1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/contact-us\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\\\/\\\/hubo-sports.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hubo-sports.com\\\/#website\",\"url\":\"https:\\\/\\\/hubo-sports.com\\\/\",\"name\":\"Hubo\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hubo-sports.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contactez-nous | Fabricant de lunettes Hubo","description":"Besoin d&#039;aide pour des masques de ski personnalis\u00e9s, des \u00e9chantillons gratuits ou pour d\u00e9marrer votre activit\u00e9\u00a0? L&#039;\u00e9quipe exp\u00e9riment\u00e9e de Hubo est l\u00e0 pour vous aider. Cliquez ici pour nous contacter.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hubo-sports.com\/fr\/contact-us\/","og_locale":"fr_FR","og_type":"article","og_title":"Contact Us | Hubo Goggle Manufacturer","og_description":"Need any assistance with custom ski goggles, free samples, or startup? The experienced Hubo team is here to help. Click to drop us a line.","og_url":"https:\/\/hubo-sports.com\/fr\/contact-us\/","og_site_name":"Hubo","article_modified_time":"2024-11-11T06:31:25+00:00","og_image":[{"url":"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/safety-goggles1.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hubo-sports.com\/contact-us\/","url":"https:\/\/hubo-sports.com\/contact-us\/","name":"Contactez-nous | Fabricant de lunettes Hubo","isPartOf":{"@id":"https:\/\/hubo-sports.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hubo-sports.com\/contact-us\/#primaryimage"},"image":{"@id":"https:\/\/hubo-sports.com\/contact-us\/#primaryimage"},"thumbnailUrl":"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/safety-goggles1.webp","datePublished":"2023-05-12T03:00:31+00:00","dateModified":"2024-11-11T06:31:25+00:00","description":"Besoin d&#039;aide pour des masques de ski personnalis\u00e9s, des \u00e9chantillons gratuits ou pour d\u00e9marrer votre activit\u00e9\u00a0? L&#039;\u00e9quipe exp\u00e9riment\u00e9e de Hubo est l\u00e0 pour vous aider. Cliquez ici pour nous contacter.","breadcrumb":{"@id":"https:\/\/hubo-sports.com\/contact-us\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hubo-sports.com\/contact-us\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/hubo-sports.com\/contact-us\/#primaryimage","url":"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/safety-goggles1.webp","contentUrl":"https:\/\/hubo-sports.com\/wp-content\/uploads\/2023\/05\/safety-goggles1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/hubo-sports.com\/contact-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/hubo-sports.com\/"},{"@type":"ListItem","position":2,"name":"Contact Us"}]},{"@type":"WebSite","@id":"https:\/\/hubo-sports.com\/#website","url":"https:\/\/hubo-sports.com\/","name":"Hubo","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hubo-sports.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/pages\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/comments?post=1796"}],"version-history":[{"count":0,"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/pages\/1796\/revisions"}],"wp:attachment":[{"href":"https:\/\/hubo-sports.com\/fr\/wp-json\/wp\/v2\/media?parent=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}